{"id":969,"date":"2022-05-09T11:47:46","date_gmt":"2022-05-09T09:47:46","guid":{"rendered":"https:\/\/palazzoprigionivenezia.com\/?p=969"},"modified":"2022-05-26T12:29:51","modified_gmt":"2022-05-26T10:29:51","slug":"ceppi-palazzo-delle-prigioni","status":"publish","type":"post","link":"https:\/\/palazzoprigionivenezia.com\/en\/ceppi-palazzo-delle-prigioni\/","title":{"rendered":"Stocks: instrument of torture of the inquisition"},"content":{"rendered":"<p>The <strong>Stocks<\/strong> are a punitive tool, used during the Middle Ages. Unlike the&nbsp;<strong>pillory<\/strong>, where the restraint boards are fixed to a pole and placed around the arms and neck of the condemned, forcing him to stand,&nbsp;<strong>stocks&nbsp;<\/strong>consist of a&nbsp;<strong>structure<\/strong>&nbsp;made specifically for the containment of the feet by locking the ankles.<\/p>\n\n\n\n<p>In the prisons they were used to immobilize the prisoner to better whip the soles of the feet.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Torture in the Middle Ages<\/strong><\/h2>\n\n\n\n<p>Widely used in&nbsp;<strong>medieval times<\/strong>, the treatment was known in much older times. It is in fact already mentioned in the&nbsp;<strong>Bible<\/strong>, where it is reserved for Paul and Silas, disciples of Jesus: \u00abHe, having received this order, threw them into the innermost cell of the prison and clasped their feet in the shackles\u00bb (Acts 5:24).<\/p>\n\n\n\n<p>In&nbsp;<strong>1989<\/strong>&nbsp;the city of&nbsp;<strong>Dermott<\/strong>,&nbsp;<strong>Arkansas<\/strong>&nbsp;(US) passed a curfew law punishable by up to thirty days in prison for the offender and&nbsp;<strong>up to two days of stocks<\/strong>&nbsp;for his parents. The initiative, however, was abandoned, because the city did not have any logs and had not even allocated funds to build them.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Curiosities about the Stocks<\/strong><\/h2>\n\n\n\n<p>In&nbsp;<strong>2020<\/strong>, during the&nbsp;<strong>COVID-19 pandemic<\/strong>, the police in Chinu, Colombia, put to the stocks for a few hours residents who had violated the mandatory quarantine regime.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Palazzo delle Prigioni in Venice: the prison and the sentences of the condemned<\/strong><\/h2>\n\n\n\n<p><strong>The Palazzo delle Prigioni<\/strong> offers the opportunity to view the instruments of torture, prisons and period clothes still today, as well as learn about the <strong>stories and legends of a distant Venice. <\/strong>A piece of history witnessing the <strong>death and torture machines<\/strong> once used as instruments of justice.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/palazzoprigionivenezia.com\/en\/visita-le-prigioni-di-piazza-san-marco\/\" target=\"_blank\" rel=\"noreferrer noopener\">Visit Palazzo delle Prigioni<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:36px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_450624161\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Strumenti-di-tortura-i ceppi-palazzo-delle-prigioni\" srcset=\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-1024x683.jpg 1024w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-300x200.jpg 300w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-768x512.jpg 768w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-1536x1024.jpg 1536w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-2048x1365.jpg 2048w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-18x12.jpg 18w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-510x340.jpg 510w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_450624161 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>I Ceppi sono uno strumento punitivo, utilizzato durante il Medioevo. A differenza della&nbsp;gogna, dove le assi di contenzione sono fissate a un palo e poste attorno alle braccia e al collo del condannato, costringendolo a stare in piedi, i&nbsp;ceppi&nbsp;sono costituiti da una&nbsp;struttura&nbsp;realizzata appositamente per il contenimento dei piedi tramite il blocco delle caviglie. Nelle carceri [&#8230;]","protected":false},"author":5,"featured_media":857,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-strumenti-giustizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>I Ceppi: strumento di tortura | Palazzo delle Prigioni Nove<\/title>\n<meta name=\"description\" content=\"I Ceppi sono uno strumento punitivo del Medioevo. In visita al Palazzo delle Prigioni percorrerai gli spazi di una delle carceri antiche.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/palazzoprigionivenezia.com\/en\/ceppi-palazzo-delle-prigioni\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I Ceppi: strumento di tortura | Palazzo delle Prigioni Nove\" \/>\n<meta property=\"og:description\" content=\"I Ceppi sono uno strumento punitivo del Medioevo. In visita al Palazzo delle Prigioni percorrerai gli spazi di una delle carceri antiche.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/palazzoprigionivenezia.com\/en\/ceppi-palazzo-delle-prigioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Palazzo delle Prigioni Nove\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-09T09:47:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-26T10:29:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adel.digitalroom@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adel.digitalroom@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/\",\"url\":\"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/\",\"name\":\"I Ceppi: strumento di tortura | Palazzo delle Prigioni Nove\",\"isPartOf\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-scaled.jpg\",\"datePublished\":\"2022-05-09T09:47:46+00:00\",\"dateModified\":\"2022-05-26T10:29:51+00:00\",\"author\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/ebd50c7166f2bc550f3d1abb8b0aa079\"},\"description\":\"I Ceppi sono uno strumento punitivo del Medioevo. In visita al Palazzo delle Prigioni percorrerai gli spazi di una delle carceri antiche.\",\"breadcrumb\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/#primaryimage\",\"url\":\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-scaled.jpg\",\"contentUrl\":\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Strumenti-di-tortura-i ceppi-palazzo-delle-prigioni\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/palazzoprigionivenezia.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ceppi: strumento di tortura dell\u2019inquisizione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#website\",\"url\":\"https:\/\/palazzoprigionivenezia.com\/\",\"name\":\"Palazzo delle Prigioni Nove\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/palazzoprigionivenezia.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/ebd50c7166f2bc550f3d1abb8b0aa079\",\"name\":\"adel.digitalroom@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b02c83cd15ca796c538b0b770a8b0dc88fcf2fcc9e4296f9466cb4ce28fe3eff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b02c83cd15ca796c538b0b770a8b0dc88fcf2fcc9e4296f9466cb4ce28fe3eff?s=96&d=mm&r=g\",\"caption\":\"adel.digitalroom@gmail.com\"},\"url\":\"https:\/\/palazzoprigionivenezia.com\/en\/author\/adel-digitalroomgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I Ceppi: strumento di tortura | Palazzo delle Prigioni Nove","description":"I Ceppi sono uno strumento punitivo del Medioevo. In visita al Palazzo delle Prigioni percorrerai gli spazi di una delle carceri antiche.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/palazzoprigionivenezia.com\/en\/ceppi-palazzo-delle-prigioni\/","og_locale":"en_GB","og_type":"article","og_title":"I Ceppi: strumento di tortura | Palazzo delle Prigioni Nove","og_description":"I Ceppi sono uno strumento punitivo del Medioevo. In visita al Palazzo delle Prigioni percorrerai gli spazi di una delle carceri antiche.","og_url":"https:\/\/palazzoprigionivenezia.com\/en\/ceppi-palazzo-delle-prigioni\/","og_site_name":"Palazzo delle Prigioni Nove","article_published_time":"2022-05-09T09:47:46+00:00","article_modified_time":"2022-05-26T10:29:51+00:00","og_image":[{"width":2560,"height":1707,"url":"http:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-scaled.jpg","type":"image\/jpeg"}],"author":"adel.digitalroom@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adel.digitalroom@gmail.com","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/","url":"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/","name":"I Ceppi: strumento di tortura | Palazzo delle Prigioni Nove","isPartOf":{"@id":"https:\/\/palazzoprigionivenezia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/#primaryimage"},"image":{"@id":"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/#primaryimage"},"thumbnailUrl":"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-scaled.jpg","datePublished":"2022-05-09T09:47:46+00:00","dateModified":"2022-05-26T10:29:51+00:00","author":{"@id":"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/ebd50c7166f2bc550f3d1abb8b0aa079"},"description":"I Ceppi sono uno strumento punitivo del Medioevo. In visita al Palazzo delle Prigioni percorrerai gli spazi di una delle carceri antiche.","breadcrumb":{"@id":"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/#primaryimage","url":"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-scaled.jpg","contentUrl":"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/03\/prigioni-12-scaled.jpg","width":2560,"height":1707,"caption":"Strumenti-di-tortura-i ceppi-palazzo-delle-prigioni"},{"@type":"BreadcrumbList","@id":"https:\/\/palazzoprigionivenezia.com\/ceppi-palazzo-delle-prigioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/palazzoprigionivenezia.com\/"},{"@type":"ListItem","position":2,"name":"Ceppi: strumento di tortura dell\u2019inquisizione"}]},{"@type":"WebSite","@id":"https:\/\/palazzoprigionivenezia.com\/#website","url":"https:\/\/palazzoprigionivenezia.com\/","name":"Palazzo delle Prigioni Nove","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/palazzoprigionivenezia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/ebd50c7166f2bc550f3d1abb8b0aa079","name":"adel.digitalroom@gmail.com","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b02c83cd15ca796c538b0b770a8b0dc88fcf2fcc9e4296f9466cb4ce28fe3eff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b02c83cd15ca796c538b0b770a8b0dc88fcf2fcc9e4296f9466cb4ce28fe3eff?s=96&d=mm&r=g","caption":"adel.digitalroom@gmail.com"},"url":"https:\/\/palazzoprigionivenezia.com\/en\/author\/adel-digitalroomgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts\/969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/comments?post=969"}],"version-history":[{"count":4,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts\/969\/revisions"}],"predecessor-version":[{"id":1050,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts\/969\/revisions\/1050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/media\/857"}],"wp:attachment":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/media?parent=969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/categories?post=969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/tags?post=969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}