{"id":653,"date":"2022-01-05T15:14:23","date_gmt":"2022-01-05T14:14:23","guid":{"rendered":"https:\/\/palazzoprigionivenezia.com\/?p=653"},"modified":"2022-01-05T15:15:47","modified_gmt":"2022-01-05T14:15:47","slug":"i-galeotti","status":"publish","type":"post","link":"https:\/\/palazzoprigionivenezia.com\/en\/i-galeotti\/","title":{"rendered":"Convicts"},"content":{"rendered":"<p><strong>Convicts<\/strong><\/p>\n\n\n\n<p>At a later stage, <strong>during the 1500s<\/strong>, the <strong>Republic of Venice<\/strong> introduced a new punishment: being sentenced to imprisonment on board the <strong>Galleys<\/strong>, the Venetian battleships. Here the prisoners would be chained up and made to row the boat instead of serving their penalty inside the overcrowded prison. At that time, it was also believed that this punishment was rehabilitating when compared to rotting away in the filthy cells. It also provided the <strong>Venetian fleet<\/strong> with free of charge rowers.<\/p>\n\n\n\n<p><strong>One year's stay<\/strong> on the galleys was equivalent to <strong>2 years' imprisonment.<\/strong> according to the prison sentence count.<\/p>\n\n\n\n<p>As for the other prisoners, those sentenced to rowing had to pay the maintenance, the <strong>legal costs<\/strong> and the acts of release.<\/p>\n\n\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_300026114\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"606\" src=\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea.jpg\" class=\"attachment-large size-large\" alt=\"galea-veneziana\" srcset=\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea.jpg 780w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea-300x233.jpg 300w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea-768x597.jpg 768w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea-15x12.jpg 15w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea-510x396.jpg 510w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_300026114 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ad un certo punto, dopo il 1500, la Repubblica di Venezia introdusse\u00a0 una nuova pena, la condanna ad essere prigionieri a bordo delle Galee, le navi da battaglia Veneziane, incatenati, come rematori anzich\u00e9 scontare la pena all&#8217; interno del sovraffollato carcere. Si riteneva, a quel tempo, che tale pena fosse anche rieducativa se paragonata al [&#8230;]","protected":false},"author":5,"featured_media":654,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prigionieri-e-galeotti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>I galeotti - Palazzo delle Prigioni Nove<\/title>\n<meta name=\"description\" content=\"Ad un certo punto, dopo il 1500, la Repubblica di Venezia introdusse\u00a0 una nuova pena, la condanna ad essere prigionieri a bordo delle Galee, le navi da battaglia Veneziane, incatenati, come rematori anzich\u00e9 scontare la pena all&#039; interno del sovraffollato carcere.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/palazzoprigionivenezia.com\/en\/i-galeotti\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I galeotti - Palazzo delle Prigioni Nove\" \/>\n<meta property=\"og:description\" content=\"Ad un certo punto, dopo il 1500, la Repubblica di Venezia introdusse\u00a0 una nuova pena, la condanna ad essere prigionieri a bordo delle Galee, le navi da battaglia Veneziane, incatenati, come rematori anzich\u00e9 scontare la pena all&#039; interno del sovraffollato carcere.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/palazzoprigionivenezia.com\/en\/i-galeotti\/\" \/>\n<meta property=\"og:site_name\" content=\"Palazzo delle Prigioni Nove\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-05T14:14:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-05T14:15:47+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adel.digitalroom@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adel.digitalroom@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/\",\"url\":\"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/\",\"name\":\"I galeotti - Palazzo delle Prigioni Nove\",\"isPartOf\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea.jpg\",\"datePublished\":\"2022-01-05T14:14:23+00:00\",\"dateModified\":\"2022-01-05T14:15:47+00:00\",\"author\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/ebd50c7166f2bc550f3d1abb8b0aa079\"},\"description\":\"Ad un certo punto, dopo il 1500, la Repubblica di Venezia introdusse\u00a0 una nuova pena, la condanna ad essere prigionieri a bordo delle Galee, le navi da battaglia Veneziane, incatenati, come rematori anzich\u00e9 scontare la pena all' interno del sovraffollato carcere.\",\"breadcrumb\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/#primaryimage\",\"url\":\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea.jpg\",\"contentUrl\":\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea.jpg\",\"width\":780,\"height\":606,\"caption\":\"galea-veneziana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/palazzoprigionivenezia.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I galeotti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#website\",\"url\":\"https:\/\/palazzoprigionivenezia.com\/\",\"name\":\"Palazzo delle Prigioni Nove\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/palazzoprigionivenezia.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/ebd50c7166f2bc550f3d1abb8b0aa079\",\"name\":\"adel.digitalroom@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b02c83cd15ca796c538b0b770a8b0dc88fcf2fcc9e4296f9466cb4ce28fe3eff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b02c83cd15ca796c538b0b770a8b0dc88fcf2fcc9e4296f9466cb4ce28fe3eff?s=96&d=mm&r=g\",\"caption\":\"adel.digitalroom@gmail.com\"},\"url\":\"https:\/\/palazzoprigionivenezia.com\/en\/author\/adel-digitalroomgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I galeotti - Palazzo delle Prigioni Nove","description":"Ad un certo punto, dopo il 1500, la Repubblica di Venezia introdusse\u00a0 una nuova pena, la condanna ad essere prigionieri a bordo delle Galee, le navi da battaglia Veneziane, incatenati, come rematori anzich\u00e9 scontare la pena all' interno del sovraffollato carcere.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/palazzoprigionivenezia.com\/en\/i-galeotti\/","og_locale":"en_GB","og_type":"article","og_title":"I galeotti - Palazzo delle Prigioni Nove","og_description":"Ad un certo punto, dopo il 1500, la Repubblica di Venezia introdusse\u00a0 una nuova pena, la condanna ad essere prigionieri a bordo delle Galee, le navi da battaglia Veneziane, incatenati, come rematori anzich\u00e9 scontare la pena all' interno del sovraffollato carcere.","og_url":"https:\/\/palazzoprigionivenezia.com\/en\/i-galeotti\/","og_site_name":"Palazzo delle Prigioni Nove","article_published_time":"2022-01-05T14:14:23+00:00","article_modified_time":"2022-01-05T14:15:47+00:00","og_image":[{"width":780,"height":606,"url":"http:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea.jpg","type":"image\/jpeg"}],"author":"adel.digitalroom@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adel.digitalroom@gmail.com","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/","url":"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/","name":"I galeotti - Palazzo delle Prigioni Nove","isPartOf":{"@id":"https:\/\/palazzoprigionivenezia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/#primaryimage"},"image":{"@id":"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/#primaryimage"},"thumbnailUrl":"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea.jpg","datePublished":"2022-01-05T14:14:23+00:00","dateModified":"2022-01-05T14:15:47+00:00","author":{"@id":"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/ebd50c7166f2bc550f3d1abb8b0aa079"},"description":"Ad un certo punto, dopo il 1500, la Repubblica di Venezia introdusse\u00a0 una nuova pena, la condanna ad essere prigionieri a bordo delle Galee, le navi da battaglia Veneziane, incatenati, come rematori anzich\u00e9 scontare la pena all' interno del sovraffollato carcere.","breadcrumb":{"@id":"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/palazzoprigionivenezia.com\/i-galeotti\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/#primaryimage","url":"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea.jpg","contentUrl":"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/galea.jpg","width":780,"height":606,"caption":"galea-veneziana"},{"@type":"BreadcrumbList","@id":"https:\/\/palazzoprigionivenezia.com\/i-galeotti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/palazzoprigionivenezia.com\/"},{"@type":"ListItem","position":2,"name":"I galeotti"}]},{"@type":"WebSite","@id":"https:\/\/palazzoprigionivenezia.com\/#website","url":"https:\/\/palazzoprigionivenezia.com\/","name":"Palazzo delle Prigioni Nove","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/palazzoprigionivenezia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/ebd50c7166f2bc550f3d1abb8b0aa079","name":"adel.digitalroom@gmail.com","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b02c83cd15ca796c538b0b770a8b0dc88fcf2fcc9e4296f9466cb4ce28fe3eff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b02c83cd15ca796c538b0b770a8b0dc88fcf2fcc9e4296f9466cb4ce28fe3eff?s=96&d=mm&r=g","caption":"adel.digitalroom@gmail.com"},"url":"https:\/\/palazzoprigionivenezia.com\/en\/author\/adel-digitalroomgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts\/653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/comments?post=653"}],"version-history":[{"count":3,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts\/653\/revisions"}],"predecessor-version":[{"id":657,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts\/653\/revisions\/657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/media\/654"}],"wp:attachment":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/media?parent=653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/categories?post=653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/tags?post=653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}