{"id":639,"date":"2022-01-05T13:19:26","date_gmt":"2022-01-05T12:19:26","guid":{"rendered":"https:\/\/palazzoprigionivenezia.com\/?p=639"},"modified":"2022-01-05T13:21:09","modified_gmt":"2022-01-05T12:21:09","slug":"le-torture","status":"publish","type":"post","link":"https:\/\/palazzoprigionivenezia.com\/en\/le-torture\/","title":{"rendered":"Torture"},"content":{"rendered":"<p><strong>Torture<\/strong><\/p>\n\n\n\n<p>In the prisons\u2019 palace <strong>, next to the rooms of the Lords of the Night<\/strong> was the <strong>torture room.<\/strong> During interrogations for certain crimes it was possible to subject prisoners to torture.<\/p>\n\n\n\n<p>Considering that fire was the main enemy to <strong>Venice<\/strong> , any method of torture using fire was avoided.\nThe main means of torture, if not the only one that the Venetians used, was <strong>rope torture <\/strong>sometimes combined with <strong>squassation<\/strong>. Victims had their wrists and elbows tied together behind their backs, then the body was lifted from behind with the rope and suspended.\nWe\u2019ll leave it to you to consider the unimaginable torment that the unfortunate victim would suffer from such torture.<\/p>\n\n\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_171111777\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"679\" src=\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-1024x682.jpg\" class=\"attachment-large size-large\" alt=\"tormento-della-corda-palazzo-delle-prigioni\" srcset=\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-1024x682.jpg 1024w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-300x200.jpg 300w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-768x511.jpg 768w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-1536x1022.jpg 1536w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-2048x1363.jpg 2048w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-18x12.jpg 18w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-510x340.jpg 510w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_171111777 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Affianco alle sale dei Signori della Notte c&#8217;era la stanza delle torture nel palazzo delle prigioni, durante gli interrogatori si potevano, solo per alcuni reati, sottoporre i prigionieri alla tortura. Considerate che il principale nemico a Venezia era il fuoco, quindi si evitava qualsiasi strumento di tortura che prevedesse utilizzo di fuoco. La principale tortura, [&#8230;]","protected":false},"author":5,"featured_media":640,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-giustizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le torture - Palazzo delle Prigioni Nove<\/title>\n<meta name=\"description\" content=\"Affianco alle sale dei Signori della Notte c&#039;era la stanza delle torture nel palazzo delle prigioni, durante gli interrogatori si potevano, solo per alcuni reati, sottoporre i prigionieri alla tortura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/palazzoprigionivenezia.com\/en\/le-torture\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le torture - Palazzo delle Prigioni Nove\" \/>\n<meta property=\"og:description\" content=\"Affianco alle sale dei Signori della Notte c&#039;era la stanza delle torture nel palazzo delle prigioni, durante gli interrogatori si potevano, solo per alcuni reati, sottoporre i prigionieri alla tortura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/palazzoprigionivenezia.com\/en\/le-torture\/\" \/>\n<meta property=\"og:site_name\" content=\"Palazzo delle Prigioni Nove\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-05T12:19:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-05T12:21:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adel.digitalroom@gmail.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adel.digitalroom@gmail.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/le-torture\/\",\"url\":\"https:\/\/palazzoprigionivenezia.com\/le-torture\/\",\"name\":\"Le torture - Palazzo delle Prigioni Nove\",\"isPartOf\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/le-torture\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/le-torture\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-scaled.jpg\",\"datePublished\":\"2022-01-05T12:19:26+00:00\",\"dateModified\":\"2022-01-05T12:21:09+00:00\",\"author\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/ebd50c7166f2bc550f3d1abb8b0aa079\"},\"description\":\"Affianco alle sale dei Signori della Notte c'era la stanza delle torture nel palazzo delle prigioni, durante gli interrogatori si potevano, solo per alcuni reati, sottoporre i prigionieri alla tortura.\",\"breadcrumb\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/le-torture\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/palazzoprigionivenezia.com\/le-torture\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/le-torture\/#primaryimage\",\"url\":\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-scaled.jpg\",\"contentUrl\":\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-scaled.jpg\",\"width\":2560,\"height\":1704,\"caption\":\"tormento-della-corda-palazzo-delle-prigioni\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/le-torture\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/palazzoprigionivenezia.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le torture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#website\",\"url\":\"https:\/\/palazzoprigionivenezia.com\/\",\"name\":\"Palazzo delle Prigioni Nove\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/palazzoprigionivenezia.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/ebd50c7166f2bc550f3d1abb8b0aa079\",\"name\":\"adel.digitalroom@gmail.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b02c83cd15ca796c538b0b770a8b0dc88fcf2fcc9e4296f9466cb4ce28fe3eff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b02c83cd15ca796c538b0b770a8b0dc88fcf2fcc9e4296f9466cb4ce28fe3eff?s=96&d=mm&r=g\",\"caption\":\"adel.digitalroom@gmail.com\"},\"url\":\"https:\/\/palazzoprigionivenezia.com\/en\/author\/adel-digitalroomgmail-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le torture - Palazzo delle Prigioni Nove","description":"Affianco alle sale dei Signori della Notte c'era la stanza delle torture nel palazzo delle prigioni, durante gli interrogatori si potevano, solo per alcuni reati, sottoporre i prigionieri alla tortura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/palazzoprigionivenezia.com\/en\/le-torture\/","og_locale":"en_GB","og_type":"article","og_title":"Le torture - Palazzo delle Prigioni Nove","og_description":"Affianco alle sale dei Signori della Notte c'era la stanza delle torture nel palazzo delle prigioni, durante gli interrogatori si potevano, solo per alcuni reati, sottoporre i prigionieri alla tortura.","og_url":"https:\/\/palazzoprigionivenezia.com\/en\/le-torture\/","og_site_name":"Palazzo delle Prigioni Nove","article_published_time":"2022-01-05T12:19:26+00:00","article_modified_time":"2022-01-05T12:21:09+00:00","og_image":[{"width":2560,"height":1704,"url":"http:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-scaled.jpg","type":"image\/jpeg"}],"author":"adel.digitalroom@gmail.com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adel.digitalroom@gmail.com","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/palazzoprigionivenezia.com\/le-torture\/","url":"https:\/\/palazzoprigionivenezia.com\/le-torture\/","name":"Le torture - Palazzo delle Prigioni Nove","isPartOf":{"@id":"https:\/\/palazzoprigionivenezia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/palazzoprigionivenezia.com\/le-torture\/#primaryimage"},"image":{"@id":"https:\/\/palazzoprigionivenezia.com\/le-torture\/#primaryimage"},"thumbnailUrl":"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-scaled.jpg","datePublished":"2022-01-05T12:19:26+00:00","dateModified":"2022-01-05T12:21:09+00:00","author":{"@id":"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/ebd50c7166f2bc550f3d1abb8b0aa079"},"description":"Affianco alle sale dei Signori della Notte c'era la stanza delle torture nel palazzo delle prigioni, durante gli interrogatori si potevano, solo per alcuni reati, sottoporre i prigionieri alla tortura.","breadcrumb":{"@id":"https:\/\/palazzoprigionivenezia.com\/le-torture\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/palazzoprigionivenezia.com\/le-torture\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/palazzoprigionivenezia.com\/le-torture\/#primaryimage","url":"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-scaled.jpg","contentUrl":"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2022\/01\/stanza-delle-torture-scaled.jpg","width":2560,"height":1704,"caption":"tormento-della-corda-palazzo-delle-prigioni"},{"@type":"BreadcrumbList","@id":"https:\/\/palazzoprigionivenezia.com\/le-torture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/palazzoprigionivenezia.com\/"},{"@type":"ListItem","position":2,"name":"Le torture"}]},{"@type":"WebSite","@id":"https:\/\/palazzoprigionivenezia.com\/#website","url":"https:\/\/palazzoprigionivenezia.com\/","name":"Palazzo delle Prigioni Nove","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/palazzoprigionivenezia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/ebd50c7166f2bc550f3d1abb8b0aa079","name":"adel.digitalroom@gmail.com","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b02c83cd15ca796c538b0b770a8b0dc88fcf2fcc9e4296f9466cb4ce28fe3eff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b02c83cd15ca796c538b0b770a8b0dc88fcf2fcc9e4296f9466cb4ce28fe3eff?s=96&d=mm&r=g","caption":"adel.digitalroom@gmail.com"},"url":"https:\/\/palazzoprigionivenezia.com\/en\/author\/adel-digitalroomgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts\/639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/comments?post=639"}],"version-history":[{"count":2,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts\/639\/revisions"}],"predecessor-version":[{"id":642,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts\/639\/revisions\/642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/media\/640"}],"wp:attachment":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/media?parent=639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/categories?post=639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/tags?post=639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}