{"id":1508,"date":"2023-02-08T13:13:28","date_gmt":"2023-02-08T12:13:28","guid":{"rendered":"https:\/\/palazzoprigionivenezia.com\/?p=1508"},"modified":"2023-02-08T13:24:24","modified_gmt":"2023-02-08T12:24:24","slug":"cosa-dicono-di-noi-ansa-2","status":"publish","type":"post","link":"https:\/\/palazzoprigionivenezia.com\/en\/cosa-dicono-di-noi-ansa-2\/","title":{"rendered":"What the newspapers say about us: il Gazzettino"},"content":{"rendered":"<div class=\"row\"  id=\"row-1287923471\">\n\n\n\t<div id=\"col-1722964528\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1590086259\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"692\" height=\"1024\" src=\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/Il-Gazzettino_nazionale-24.01.23-692x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/Il-Gazzettino_nazionale-24.01.23-692x1024.png 692w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/Il-Gazzettino_nazionale-24.01.23-203x300.png 203w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/Il-Gazzettino_nazionale-24.01.23-768x1137.png 768w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/Il-Gazzettino_nazionale-24.01.23-8x12.png 8w, https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/Il-Gazzettino_nazionale-24.01.23.png 780w\" sizes=\"auto, (max-width: 692px) 100vw, 692px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1590086259 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":1512,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicono-di-noi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cosa dicono di noi i giornali: il Gazzettino - Palazzo delle Prigioni Nove<\/title>\n<meta name=\"description\" content=\"Scopri cosa dicono di i giornali.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/palazzoprigionivenezia.com\/en\/cosa-dicono-di-noi-ansa-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cosa dicono di noi i giornali: il Gazzettino - Palazzo delle Prigioni Nove\" \/>\n<meta property=\"og:description\" content=\"Scopri cosa dicono di i giornali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/palazzoprigionivenezia.com\/en\/cosa-dicono-di-noi-ansa-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Palazzo delle Prigioni Nove\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-08T12:13:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T12:24:24+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/IMG_6586-ridotto-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"831\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assistace\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"assistace\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/\",\"url\":\"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/\",\"name\":\"Cosa dicono di noi i giornali: il Gazzettino - Palazzo delle Prigioni Nove\",\"isPartOf\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/IMG_6586-ridotto-scaled.jpg\",\"datePublished\":\"2023-02-08T12:13:28+00:00\",\"dateModified\":\"2023-02-08T12:24:24+00:00\",\"author\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/c9adb5ae02ace72484c4614bc8161e1f\"},\"description\":\"Scopri cosa dicono di i giornali.\",\"breadcrumb\":{\"@id\":\"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/#primaryimage\",\"url\":\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/IMG_6586-ridotto-scaled.jpg\",\"contentUrl\":\"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/IMG_6586-ridotto-scaled.jpg\",\"width\":2560,\"height\":831},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/palazzoprigionivenezia.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosa dicono di noi i giornali: il Gazzettino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#website\",\"url\":\"https:\/\/palazzoprigionivenezia.com\/\",\"name\":\"Palazzo delle Prigioni Nove\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/palazzoprigionivenezia.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/c9adb5ae02ace72484c4614bc8161e1f\",\"name\":\"assistace\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/224d694f1d3c163886576affffd5344d14f3462c2785965d942bcefe798e69ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/224d694f1d3c163886576affffd5344d14f3462c2785965d942bcefe798e69ca?s=96&d=mm&r=g\",\"caption\":\"assistace\"},\"url\":\"https:\/\/palazzoprigionivenezia.com\/en\/author\/assistace\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cosa dicono di noi i giornali: il Gazzettino - Palazzo delle Prigioni Nove","description":"Scopri cosa dicono di i giornali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/palazzoprigionivenezia.com\/en\/cosa-dicono-di-noi-ansa-2\/","og_locale":"en_GB","og_type":"article","og_title":"Cosa dicono di noi i giornali: il Gazzettino - Palazzo delle Prigioni Nove","og_description":"Scopri cosa dicono di i giornali.","og_url":"https:\/\/palazzoprigionivenezia.com\/en\/cosa-dicono-di-noi-ansa-2\/","og_site_name":"Palazzo delle Prigioni Nove","article_published_time":"2023-02-08T12:13:28+00:00","article_modified_time":"2023-02-08T12:24:24+00:00","og_image":[{"width":2560,"height":831,"url":"http:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/IMG_6586-ridotto-scaled.jpg","type":"image\/jpeg"}],"author":"assistace","twitter_card":"summary_large_image","twitter_misc":{"Written by":"assistace","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/","url":"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/","name":"Cosa dicono di noi i giornali: il Gazzettino - Palazzo delle Prigioni Nove","isPartOf":{"@id":"https:\/\/palazzoprigionivenezia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/#primaryimage"},"image":{"@id":"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/#primaryimage"},"thumbnailUrl":"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/IMG_6586-ridotto-scaled.jpg","datePublished":"2023-02-08T12:13:28+00:00","dateModified":"2023-02-08T12:24:24+00:00","author":{"@id":"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/c9adb5ae02ace72484c4614bc8161e1f"},"description":"Scopri cosa dicono di i giornali.","breadcrumb":{"@id":"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/#primaryimage","url":"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/IMG_6586-ridotto-scaled.jpg","contentUrl":"https:\/\/palazzoprigionivenezia.com\/wp-content\/uploads\/2023\/02\/IMG_6586-ridotto-scaled.jpg","width":2560,"height":831},{"@type":"BreadcrumbList","@id":"https:\/\/palazzoprigionivenezia.com\/cosa-dicono-di-noi-ansa-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/palazzoprigionivenezia.com\/"},{"@type":"ListItem","position":2,"name":"Cosa dicono di noi i giornali: il Gazzettino"}]},{"@type":"WebSite","@id":"https:\/\/palazzoprigionivenezia.com\/#website","url":"https:\/\/palazzoprigionivenezia.com\/","name":"Palazzo delle Prigioni Nove","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/palazzoprigionivenezia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/c9adb5ae02ace72484c4614bc8161e1f","name":"assistace","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/palazzoprigionivenezia.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/224d694f1d3c163886576affffd5344d14f3462c2785965d942bcefe798e69ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/224d694f1d3c163886576affffd5344d14f3462c2785965d942bcefe798e69ca?s=96&d=mm&r=g","caption":"assistace"},"url":"https:\/\/palazzoprigionivenezia.com\/en\/author\/assistace\/"}]}},"_links":{"self":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts\/1508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/comments?post=1508"}],"version-history":[{"count":5,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts\/1508\/revisions"}],"predecessor-version":[{"id":1521,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/posts\/1508\/revisions\/1521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/media\/1512"}],"wp:attachment":[{"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/media?parent=1508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/categories?post=1508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palazzoprigionivenezia.com\/en\/wp-json\/wp\/v2\/tags?post=1508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}